{"id":2249,"date":"2018-01-02T15:16:04","date_gmt":"2018-01-02T15:16:04","guid":{"rendered":"https:\/\/www.salentodolcevita.com\/blog\/?p=2079"},"modified":"2019-01-21T15:04:44","modified_gmt":"2019-01-21T14:04:44","slug":"2018-le-migliori-destinazioni-per-chi-ama-i-viaggi-e-il-design-2","status":"publish","type":"post","link":"https:\/\/www.salentodolcevita.com\/blog\/fr\/2018-le-migliori-destinazioni-per-chi-ama-i-viaggi-e-il-design-2\/","title":{"rendered":"2018 &#8211; Les meilleures destinations de vacances pour les amateurs des voyages et du design"},"content":{"rendered":"<p>Nous croyons que le style de vie et l&rsquo;histoire d&rsquo;un pays sont beaucoup plus que des monuments ou de la cuisine. \u00c0 SalentoDolceVita, nous aimons conna\u00eetre et vivre de nouveaux endroits en les regardant &#8230; m\u00eame de l&rsquo;int\u00e9rieur des maisons locales.<\/p>\n<p>Aujourd&rsquo;hui, nous allons vous montrer comment le design local typique influence les modes de vie locaux et nous allons vous parler de certaines endroits qui nous donnera de nouvelles id\u00e9es pour notre vie quotidienne.<\/p>\n<h3><strong>Danemark pour en savoir plus sur la vie en &#8230; hygge<\/strong><\/h3>\n<figure id=\"attachment_2080\" aria-describedby=\"caption-attachment-2080\" style=\"width: 660px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-2080\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056-1024x690.jpg\" alt=\"Viaggia in Danimarca e impara lo stile Hygge \" width=\"660\" height=\"445\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056-1024x690.jpg 1024w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056-300x202.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056-768x518.jpg 768w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/thought-catalog-188056.jpg 2048w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><figcaption id=\"caption-attachment-2080\" class=\"wp-caption-text\">Viaggia in Danimarca e impara lo stile Hygge<\/figcaption><\/figure>\n<p>Que ce soit Copenhague ou une petite ville, le Danemark est une destination \u00e0 consid\u00e9rer en 2018.<\/p>\n<p>Non seulement pour son atmosph\u00e8re d\u00e9tendue, mais aussi pour le sens de l&rsquo;accueil et la lin\u00e9arit\u00e9 de tous les int\u00e9rieurs, que ce soit une auberge ou une maison historique de Copenhague ou une maison en bois maison dans le Jutland.<\/p>\n<p>Ici vous conna\u00eetrez le sens de \u00ab\u00a0Hygge\u00a0\u00bb, le bonheur contenu dans les petites choses de la maison et de la vie quotidienne.<br \/>\n\u00c9liminer les trucs superflus et donner de l&rsquo;espace \u00e0 la philosophie du logement de ce pays.<\/p>\n<p>Au Danemark, chez les maisons, vous ne verrez gu\u00e8re de salons inoccup\u00e9s pleins de porcelaine. Vous verrez\u00a0des\u00a0objets\u00a0utiles pour le bien-\u00eatre de ceux qui vivent ls espaces et pour les invit\u00e9s.<br \/>\nAllez au Danemark et ramenez un peu de hygge dans votre vie.<\/p>\n<h3 style=\"text-align: center;\">Lisez aussi<br \/>\n<a href=\"https:\/\/www.salentodolcevita.com\/blog\/stile-nordico-e-hygge-in-riva-al-mare-3-ville-del-salento-e-il-fascino-delle-contraddizioni\/?lang=fr\" target=\"_blank\" rel=\"noopener\">Style Scandinave et \u00ab\u00a0Hygge\u00a0\u00bb \u2026 sur la mer<\/a><\/h3>\n<h3>Su\u00e8de, pour\u00a0apporter le \u00ab\u00a0Lagom\u00a0\u00bb dans votre vie<\/h3>\n<figure id=\"attachment_1905\" aria-describedby=\"caption-attachment-1905\" style=\"width: 660px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1905\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12-1024x683.jpg\" alt=\"Villa Caroma Kitchen dinning room - booking@salentodolcevita.com \" width=\"660\" height=\"440\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12-1024x683.jpg 1024w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12-300x200.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12-768x512.jpg 768w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/09\/Villa-Caroma-Kitchen-dinning-room-12.jpg 1080w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><figcaption id=\"caption-attachment-1905\" class=\"wp-caption-text\">Villa Caroma Kitchen dinning room &#8211; booking@salentodolcevita.com<\/figcaption><\/figure>\n<p>Restons dans le nord et allons en Su\u00e8de. M\u00eame les Su\u00e9dois ont un mot magique qui d\u00e9crit une vision du bonheur qui se manifeste dans l&rsquo;ameublement: <em>Lagom<\/em>.<\/p>\n<p>Extrait du\u00a0proverbe local <em>Lagom \u00e4r b\u00e4st<\/em> (pas trop, pas trop peu, le just), ce mot est devenu une philosophie virale non seulement dans l&rsquo;ameublement mais dans le style de vie qui s&rsquo;y rattache. Le style Lagom passe par la r\u00e9utilisation, le recyclage cr\u00e9atif, l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie et l&rsquo;abandon des colles synth\u00e9tiques ainsi que de mauvaises habitudes.<\/p>\n<p>En Su\u00e8de, remarquez la lumi\u00e8re qui traverse les fen\u00eatres et \u00e9claire autant que possible\u00a0pendant les (souvent peu) heures de lumi\u00e8re.\u00a0Remarquez aussi les petits jardins dans les int\u00e9rieurs des maisons, qui servent pour donner des ingredients sains \u00e0 la cuisine.<\/p>\n<h3><strong>Cuba:\u00a0la\u00a0<em>casa particular<\/em><\/strong><\/h3>\n<figure id=\"attachment_2081\" aria-describedby=\"caption-attachment-2081\" style=\"width: 660px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-2081\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174-1024x683.jpg\" alt=\"casa particular a cuba- viaggi e design per il 2018 \" width=\"660\" height=\"440\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174-1024x683.jpg 1024w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174-300x200.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174-768x512.jpg 768w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/augustin-de-montesquiou-346174.jpg 2048w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><figcaption id=\"caption-attachment-2081\" class=\"wp-caption-text\">ph. Augustin De Montesquiou &#8211; unsplash<\/figcaption><\/figure>\n<p>Cuba doit \u00eatre une de vos destinations en 2018 pour de nombreuses raisons, en commen\u00e7ant par le fait qu&rsquo;elle change rapidement et que certains aspects de l&rsquo;unicit\u00e9 culturelle, encore \u00e9vidents en 2018, n&rsquo;existeront plus en 2019, soit parce qu&rsquo;elle est maintenant travers\u00e9e comme jamais avant par les premiers projets de nouvelle ferveur culturelle. C&rsquo;est un moment magique pour l&rsquo;archipel des Cara\u00efbes.<\/p>\n<p>La casa particular\u00a0est l&rsquo;un des choix d&rsquo;h\u00e9bergement les plus int\u00e9ressants car elle vous permet de conna\u00eetre la vie locale&#8230; de l&rsquo;int\u00e9rieur.<br \/>\nCe sont des maisons priv\u00e9es o\u00f9 les touristes et les voyageurs peuvent trouver un lit et de la nourriture, souvent profiter des moments \u00e0 partager avec les propri\u00e9taires.<\/p>\n<p>Le style essentiel et color\u00e9 donnera une touche de forte tipicit\u00e9 \u00e0 votre s\u00e9jour et \u00e0 partir des mots et des histoires de vos invit\u00e9s, vous apprendrez beaucoup plus que vous ne pouvez jamais faire un livre ou un documentaire.<\/p>\n<h3 style=\"text-align: center;\">Lisez aussi<\/h3>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/www.salentodolcevita.com\/blog\/centri-storici-deuropa-conoscerli-dalla-finestra-di-un-appartamento\/?lang=fr\" target=\"_blank\" rel=\"noopener\">Les meilleures vieilles villes europ\u00e9ennes, depuis la fen\u00eatre d\u2019un appartement<\/a><\/h3>\n<h3>Le country et l&rsquo;art dans les maisons italiennes<\/h3>\n<p>Vous pouvez toujours trouver de nouvelles id\u00e9es et inspirations lorsque vous voyagez dans notre pays merveilleux et vari\u00e9. Et nous voulons partir de notre belle r\u00e9gion, les Pouilles, et de notre r\u00e9gion sub-g\u00e9ographique du Salento.<\/p>\n<p><strong>Commen\u00e7ons par le Salento et ses r\u00e9sidences d&rsquo;art.<\/strong><\/p>\n<div id='gallery-5' class='gallery galleryid-2249 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/03\/casa-artes-per-insta-story-.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\"><img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"650\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/03\/casa-artes-per-insta-story-.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-5-1581\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/03\/casa-artes-per-insta-story-.jpg 970w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/03\/casa-artes-per-insta-story--300x201.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/03\/casa-artes-per-insta-story--768x515.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-1581'>\n\t\t\t\tDettaglio di Palazzo Artes &#8211; booking@salentodolcevita.com \n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1180\" height=\"650\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-5-1719\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior.jpg 1180w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior-300x165.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior-768x423.jpg 768w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/05\/casa-artes-interior-1024x564.jpg 1024w\" sizes=\"auto, (max-width: 1180px) 100vw, 1180px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-5-1719'>\n\t\t\t\tbooking@salentodolcevita.com \n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Le Salento abrite des r\u00e9sidences cach\u00e9es au c\u0153ur des centres historiques, \u00e0 Lecce et dans les villes de la banlieue, ainsi que d&rsquo;anciennes fermes restaur\u00e9es, o\u00f9 les objets anciens s&rsquo;alternent avec des \u0153uvres d&rsquo;art uniques, par exemple dans le magnifique <a href=\"https:\/\/www.salentodolcevita.com\/fr\/vacanze\/villa\/otranto\/410-palazzo-artes.htm\" target=\"_blank\" rel=\"noopener\">Palazzo Artes<\/a> et <a href=\"https:\/\/www.salentodolcevita.com\/fr\/vacanze\/villa\/tiggiano\/372-casa-goccia.htm\" target=\"_blank\" rel=\"noopener\">Casa Goccia<\/a> respectivement \u00e0 Otranto et Tiggiano.<\/p>\n<div id='gallery-6' class='gallery galleryid-2249 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/Casa-Goccia-libreria-.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"387\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/Casa-Goccia-libreria-.jpg\" class=\"attachment-large size-large\" alt=\"Casa Goccia, Tiggiano, Salento - booking@salentodolcevita.com\" aria-describedby=\"gallery-6-1647\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/Casa-Goccia-libreria-.jpg 920w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/Casa-Goccia-libreria--300x176.jpg 300w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/Casa-Goccia-libreria--768x450.jpg 768w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-1647'>\n\t\t\t\tCasa Goccia, Tiggiano, Salento &#8211; booking@salentodolcevita.com \n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/casa-goccia-2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\"><img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"550\" src=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/casa-goccia-2.jpg\" class=\"attachment-large size-large\" alt=\"\" aria-describedby=\"gallery-6-1648\" srcset=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/casa-goccia-2.jpg 617w, https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2017\/04\/casa-goccia-2-300x267.jpg 300w\" sizes=\"auto, (max-width: 617px) 100vw, 617px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-6-1648'>\n\t\t\t\tCasa Goccia &#8211; Tiggiano &#8211; \n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Si, en revanche, vous voulez en savoir plus sur les anciennes traditions agricoles, vous pouvez chercher un h\u00e9bergement dans un trullo de la Vall\u00e9e d&rsquo;Itria et\u00a0avoir inspiration des instruments anciens transform\u00e9s en\u00a0id\u00e9es d\u00e9coratives destin\u00e9es \u00e0 une nouvelle utilisation moderne .<\/p>\n<p>Un autre style r\u00e9gional,\u00a0mais tr\u00e8s different,\u00a0on le trouve chez la Toscana. Vivez quelques jours dans une ancienne ferme dans la vall\u00e9e du Chianti ou Val d&rsquo;Orcia, et d\u00e9couvrez l&rsquo;utilit\u00e9 thermique ainsi que\u00a0ornementale des briques rouges, typiques de l&rsquo;architecture et de l&rsquo;int\u00e9rieur local.<\/p>\n<h3>A Kiev, pour le plus important salon de design d&rsquo;int\u00e9rieur<\/h3>\n<p>La magnifique capitale de l&rsquo;Ukraine accueille chaque ann\u00e9e, en f\u00e9vrier, l&rsquo;une des plus importantes expositions d\u00e9di\u00e9es au design d&rsquo;int\u00e9rieur.<\/p>\n<p>INTERIOR MEBEL &#8211; Salon du mobilier, de l&rsquo;\u00e9clairage et de la d\u00e9coration &#8211; se tiendra du 7 au 10 f\u00e9vrier 2018 \u00e0 IEC, le centre d&rsquo;exposition le plus moderne de Kiev.<\/p>\n<h3 style=\"text-align: center;\">\u00c0 vous tous, nous souhaitons un an voyage plein de voyages, d&rsquo;id\u00e9es et d&rsquo;inspiration!<\/h3>\n<h3 style=\"text-align: center;\">Suivez-nous aussi sur<\/h3>\n<h3 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.instagram.com\/salentodolcevita\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>,\u00a0<a href=\"https:\/\/www.facebook.com\/Pouillesmaisonsdecharme\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>\u00a0and<a href=\"https:\/\/twitter.com\/Apuliavillas\" target=\"_blank\" rel=\"noopener\">\u00a0Twitter<\/a>\u00a0<\/strong><\/h3>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Nous croyons que le style de vie et l&rsquo;histoire d&rsquo;un pays sont beaucoup plus que des monuments ou de la cuisine. \u00c0 SalentoDolceVita, nous aimons conna\u00eetre et vivre de nouveaux endroits en les regardant &#8230; m\u00eame de l&rsquo;int\u00e9rieur des maisons locales. Aujourd&rsquo;hui, nous allons vous montrer comment le design local typique influence les modes de vie locaux et nous allons vous parler de certaines endroits qui nous donnera de nouvelles&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[44,49,50,112,133,291,309,313,323,341,347,470,482,605,647,673],"class_list":["post-2249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-apulia","tag-art","tag-arte","tag-casa","tag-charme","tag-interior","tag-italy","tag-itinerary","tag-lecce","tag-luxury-homes","tag-maison","tag-pouilles","tag-puglia","tag-travel","tag-viaggio","tag-voyage"],"yoast_head":"<title>2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design - Le Blog de SalentoDolceVita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]2018. Le migliori destinazioni per chi ama i viaggi e il design[:en]2018 - The best destinations for travel &amp; design lovers [:fr]2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design[:] - Le Blog de SalentoDolceVita\" \/>\n<meta property=\"og:description\" content=\"Nous croyons que le style de vie et l&rsquo;histoire d&rsquo;un pays sont beaucoup plus que des monuments ou de la cuisine. \u00c0 SalentoDolceVita, nous aimons conna\u00eetre et vivre de nouveaux endroits en les regardant &#8230; m\u00eame de l&rsquo;int\u00e9rieur des maisons locales. Aujourd&rsquo;hui, nous allons vous montrer comment le design local typique influence les modes de vie locaux et nous allons vous parler de certaines endroits qui nous donnera de nouvelles&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog de SalentoDolceVita\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-02T15:16:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-21T14:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SalentoDolceVita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SalentoDolceVita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/\"},\"author\":{\"name\":\"SalentoDolceVita\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/afc29793311aac780f6f1b9f433ab86d\"},\"headline\":\"2018 &#8211; Les meilleures destinations de vacances pour les amateurs des voyages et du design\",\"datePublished\":\"2018-01-02T15:16:04+00:00\",\"dateModified\":\"2019-01-21T14:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/\"},\"wordCount\":2869,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/andrew-neel-182861.jpg\",\"keywords\":[\"apulia\",\"art\",\"arte\",\"casa\",\"charme\",\"interior\",\"Italy\",\"itinerary\",\"Lecce\",\"luxury homes\",\"maison\",\"Pouilles\",\"puglia\",\"travel\",\"viaggio\",\"voyage\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/\",\"url\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/\",\"name\":\"[:it]2018. Le migliori destinazioni per chi ama i viaggi e il design[:en]2018 - The best destinations for travel & design lovers [:fr]2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design[:] - Le Blog de SalentoDolceVita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/andrew-neel-182861.jpg\",\"datePublished\":\"2018-01-02T15:16:04+00:00\",\"dateModified\":\"2019-01-21T14:04:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/andrew-neel-182861.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/andrew-neel-182861.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"ph andrew neel - unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/en\\\/2018-the-best-destinations-for-travel-design-lovers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2018 &#8211; The best destinations for travel &#038; design lovers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/\",\"name\":\"Le Blog de SalentoDolceVita\",\"description\":\"Le guide d\u00e9finitif de vos vacances dans le Salento\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#organization\",\"name\":\"SalentoDolceVita\",\"url\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-rosso-su-bianco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-rosso-su-bianco.jpg\",\"width\":171,\"height\":116,\"caption\":\"SalentoDolceVita\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salentodolcevita.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/afc29793311aac780f6f1b9f433ab86d\",\"name\":\"SalentoDolceVita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g\",\"caption\":\"SalentoDolceVita\"}}]}<\/script>","yoast_head_json":{"title":"[:it]2018. Le migliori destinazioni per chi ama i viaggi e il design[:en]2018 - The best destinations for travel & design lovers [:fr]2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design[:] - Le Blog de SalentoDolceVita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/","og_locale":"fr_FR","og_type":"article","og_title":"[:it]2018. Le migliori destinazioni per chi ama i viaggi e il design[:en]2018 - The best destinations for travel & design lovers [:fr]2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design[:] - Le Blog de SalentoDolceVita","og_description":"Nous croyons que le style de vie et l&rsquo;histoire d&rsquo;un pays sont beaucoup plus que des monuments ou de la cuisine. \u00c0 SalentoDolceVita, nous aimons conna\u00eetre et vivre de nouveaux endroits en les regardant &#8230; m\u00eame de l&rsquo;int\u00e9rieur des maisons locales. Aujourd&rsquo;hui, nous allons vous montrer comment le design local typique influence les modes de vie locaux et nous allons vous parler de certaines endroits qui nous donnera de nouvelles&hellip;","og_url":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/","og_site_name":"Le Blog de SalentoDolceVita","article_published_time":"2018-01-02T15:16:04+00:00","article_modified_time":"2019-01-21T14:04:44+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg","type":"image\/jpeg"}],"author":"SalentoDolceVita","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"SalentoDolceVita","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#article","isPartOf":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/"},"author":{"name":"SalentoDolceVita","@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#\/schema\/person\/afc29793311aac780f6f1b9f433ab86d"},"headline":"2018 &#8211; Les meilleures destinations de vacances pour les amateurs des voyages et du design","datePublished":"2018-01-02T15:16:04+00:00","dateModified":"2019-01-21T14:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/"},"wordCount":2869,"publisher":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#organization"},"image":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg","keywords":["apulia","art","arte","casa","charme","interior","Italy","itinerary","Lecce","luxury homes","maison","Pouilles","puglia","travel","viaggio","voyage"],"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/","url":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/","name":"[:it]2018. Le migliori destinazioni per chi ama i viaggi e il design[:en]2018 - The best destinations for travel & design lovers [:fr]2018 - Les meilleures destinations de vacances pour les amateurs des voyages et du design[:] - Le Blog de SalentoDolceVita","isPartOf":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#primaryimage"},"image":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg","datePublished":"2018-01-02T15:16:04+00:00","dateModified":"2019-01-21T14:04:44+00:00","breadcrumb":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#primaryimage","url":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg","contentUrl":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2018\/01\/andrew-neel-182861.jpg","width":2048,"height":1365,"caption":"ph andrew neel - unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salentodolcevita.com\/blog\/en\/2018-the-best-destinations-for-travel-design-lovers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salentodolcevita.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"2018 &#8211; The best destinations for travel &#038; design lovers"}]},{"@type":"WebSite","@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#website","url":"https:\/\/www.salentodolcevita.com\/blog\/it\/","name":"Le Blog de SalentoDolceVita","description":"Le guide d\u00e9finitif de vos vacances dans le Salento","publisher":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salentodolcevita.com\/blog\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#organization","name":"SalentoDolceVita","url":"https:\/\/www.salentodolcevita.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2019\/01\/logo-rosso-su-bianco.jpg","contentUrl":"https:\/\/www.salentodolcevita.com\/blog\/wp-content\/uploads\/2019\/01\/logo-rosso-su-bianco.jpg","width":171,"height":116,"caption":"SalentoDolceVita"},"image":{"@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salentodolcevita.com\/blog\/it\/#\/schema\/person\/afc29793311aac780f6f1b9f433ab86d","name":"SalentoDolceVita","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16f2d5f1946984b886d3ae797f38cdc22ba33791260f7916bea6e35df7f6c1c4?s=96&d=mm&r=g","caption":"SalentoDolceVita"}}]}},"_links":{"self":[{"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=2249"}],"version-history":[{"count":1,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2249\/revisions"}],"predecessor-version":[{"id":2721,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2249\/revisions\/2721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/media\/2082"}],"wp:attachment":[{"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=2249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=2249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salentodolcevita.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}